{"id":95,"date":"2019-06-18T12:34:48","date_gmt":"2019-06-18T12:34:48","guid":{"rendered":"https:\/\/parkofideas.com\/renroll\/demo3\/?page_id=95"},"modified":"2023-07-14T15:01:19","modified_gmt":"2023-07-14T15:01:19","slug":"qui-som","status":"publish","type":"page","link":"https:\/\/motorental.cat\/es\/qui-som\/","title":{"rendered":"Qui\u00e9nes somos"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"95\" class=\"elementor elementor-95\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-71180e7 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"71180e7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-35e91ef\" data-id=\"35e91ef\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-950359a elementor-widget elementor-widget-templines-page-header\" data-id=\"950359a\" data-element_type=\"widget\" data-widget_type=\"templines-page-header.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t<header\n\t\tclass=\"l-section h-round c-page-header c-page-header--header-type-2\" style=\"background-image:url(https:\/\/motorental.cat\/wp-content\/uploads\/2020\/02\/renroll-0845964202.jpg)\">\n\t\t<div class=\"c-page-header__wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t<h1 class=\"c-page-header__title\">Qui\u00e9nes somos<\/h1>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/header>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c305cd3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c305cd3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-602804c\" data-id=\"602804c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-37bccc3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"37bccc3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c25e4d7\" data-id=\"c25e4d7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e97d3e0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e97d3e0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e365dd4\" data-id=\"e365dd4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a0ab38 elementor-widget elementor-widget-text-editor\" data-id=\"8a0ab38\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.1 - 15-02-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Moto Rental Costa Brava ofrece un servicio de alquiler de motos con sede en l'Escala, disponemos de scooters 125cc y motos el\u00e9ctricas.<\/p><p>\u00a0<\/p><p>Somos un equipo joven que nos gusta mucho nuestro trabajo, es por eso que estamos en constante evoluci\u00f3n, adapt\u00e1ndonos a las nuevas tecnolog\u00edas para poder ofrecer un servicio c\u00f3modo, r\u00e1pido y adaptado a las necesidades de cada cliente.<\/p><p>\u00a0<\/p><p>Formamos parte de la empresa matriz Motor l'Escala la cual cuenta con m\u00e1s de 20 a\u00f1os de experiencia en el sector de la automoci\u00f3n y puede ofrecer un servicio integral de movilidad: Venta de veh\u00edculos nuevos y de ocasi\u00f3n, servicio postventa, reparaci\u00f3n mec\u00e1nica, de carrocer\u00eda y alquiler de veh\u00edculos.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Qui som Moto Rental Costa Brava ofereix un servei de lloguer de motos amb base&hellip;<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":[],"_links":{"self":[{"href":"https:\/\/motorental.cat\/es\/wp-json\/wp\/v2\/pages\/95"}],"collection":[{"href":"https:\/\/motorental.cat\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/motorental.cat\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/motorental.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/motorental.cat\/es\/wp-json\/wp\/v2\/comments?post=95"}],"version-history":[{"count":13,"href":"https:\/\/motorental.cat\/es\/wp-json\/wp\/v2\/pages\/95\/revisions"}],"predecessor-version":[{"id":2672,"href":"https:\/\/motorental.cat\/es\/wp-json\/wp\/v2\/pages\/95\/revisions\/2672"}],"wp:attachment":[{"href":"https:\/\/motorental.cat\/es\/wp-json\/wp\/v2\/media?parent=95"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}